{"id":462,"count":7,"description":"","link":"https:\/\/beonmove.gr\/el\/product-category\/kalson-kaltses\/kaltses\/girls-el\/","name":"\u039a\u03bf\u03c1\u03af\u03c4\u03c3\u03b9\u03b1","slug":"girls-el","taxonomy":"product_cat","parent":460,"meta":{"order":["35"],"_wc_facebook_google_product_category":[""],"_wc_facebook_enhanced_catalog_attributes___optional_selector":[null],"product_count_product_cat":["7"],"theplus_transient_widgets":["a:0:{}"],"display_type":[""],"thumbnail_id":[null]},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u039a\u03bf\u03c1\u03af\u03c4\u03c3\u03b9\u03b1 Category - Be On Move<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beonmove.gr\/el\/product-category\/kalson-kaltses\/kaltses\/girls-el\/\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u039a\u03bf\u03c1\u03af\u03c4\u03c3\u03b9\u03b1 Category - Be On Move\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beonmove.gr\/el\/product-category\/kalson-kaltses\/kaltses\/girls-el\/\" \/>\n<meta property=\"og:site_name\" content=\"Be On Move\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/product-category\\\/kalson-kaltses\\\/kaltses\\\/girls-el\\\/\",\"url\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/product-category\\\/kalson-kaltses\\\/kaltses\\\/girls-el\\\/\",\"name\":\"\u039a\u03bf\u03c1\u03af\u03c4\u03c3\u03b9\u03b1 Category - Be On Move\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/product-category\\\/kalson-kaltses\\\/kaltses\\\/girls-el\\\/#breadcrumb\"},\"inLanguage\":\"el\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/product-category\\\/kalson-kaltses\\\/kaltses\\\/girls-el\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/archikh\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u039a\u03b1\u03bb\u03c3\u03cc\u03bd &amp; \u039a\u03ac\u03bb\u03c4\u03c3\u03b5\u03c2\",\"item\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/product-category\\\/kalson-kaltses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u039a\u03ac\u03bb\u03c4\u03c3\u03b5\u03c2\",\"item\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/product-category\\\/kalson-kaltses\\\/kaltses\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u039a\u03bf\u03c1\u03af\u03c4\u03c3\u03b9\u03b1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/#website\",\"url\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/\",\"name\":\"Be On Move\",\"description\":\"BeOnMove at Heraklion Crete is a retail shop for dancers, athletes, trainees with dancewear, danceshoes and premium activewear brands.\",\"publisher\":{\"@id\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/#organization\",\"name\":\"BeOnMove\",\"url\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beonmove.gr\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Logo_200.png\",\"contentUrl\":\"https:\\\/\\\/beonmove.gr\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Logo_200.png\",\"width\":200,\"height\":173,\"caption\":\"BeOnMove\"},\"image\":{\"@id\":\"https:\\\/\\\/beonmove.gr\\\/el\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beonmove\\\/\",\"https:\\\/\\\/www.instagram.com\\\/be_on_move\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC5WA7H8ownrvq7OaoVBDmSQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u039a\u03bf\u03c1\u03af\u03c4\u03c3\u03b9\u03b1 Category - Be On Move","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beonmove.gr\/el\/product-category\/kalson-kaltses\/kaltses\/girls-el\/","og_locale":"el_GR","og_type":"article","og_title":"\u039a\u03bf\u03c1\u03af\u03c4\u03c3\u03b9\u03b1 Category - Be On Move","og_url":"https:\/\/beonmove.gr\/el\/product-category\/kalson-kaltses\/kaltses\/girls-el\/","og_site_name":"Be On Move","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/beonmove.gr\/el\/product-category\/kalson-kaltses\/kaltses\/girls-el\/","url":"https:\/\/beonmove.gr\/el\/product-category\/kalson-kaltses\/kaltses\/girls-el\/","name":"\u039a\u03bf\u03c1\u03af\u03c4\u03c3\u03b9\u03b1 Category - Be On Move","isPartOf":{"@id":"https:\/\/beonmove.gr\/el\/#website"},"breadcrumb":{"@id":"https:\/\/beonmove.gr\/el\/product-category\/kalson-kaltses\/kaltses\/girls-el\/#breadcrumb"},"inLanguage":"el"},{"@type":"BreadcrumbList","@id":"https:\/\/beonmove.gr\/el\/product-category\/kalson-kaltses\/kaltses\/girls-el\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beonmove.gr\/el\/archikh\/"},{"@type":"ListItem","position":2,"name":"\u039a\u03b1\u03bb\u03c3\u03cc\u03bd &amp; \u039a\u03ac\u03bb\u03c4\u03c3\u03b5\u03c2","item":"https:\/\/beonmove.gr\/el\/product-category\/kalson-kaltses\/"},{"@type":"ListItem","position":3,"name":"\u039a\u03ac\u03bb\u03c4\u03c3\u03b5\u03c2","item":"https:\/\/beonmove.gr\/el\/product-category\/kalson-kaltses\/kaltses\/"},{"@type":"ListItem","position":4,"name":"\u039a\u03bf\u03c1\u03af\u03c4\u03c3\u03b9\u03b1"}]},{"@type":"WebSite","@id":"https:\/\/beonmove.gr\/el\/#website","url":"https:\/\/beonmove.gr\/el\/","name":"Be On Move","description":"BeOnMove at Heraklion Crete is a retail shop for dancers, athletes, trainees with dancewear, danceshoes and premium activewear brands.","publisher":{"@id":"https:\/\/beonmove.gr\/el\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beonmove.gr\/el\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"},{"@type":"Organization","@id":"https:\/\/beonmove.gr\/el\/#organization","name":"BeOnMove","url":"https:\/\/beonmove.gr\/el\/","logo":{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/beonmove.gr\/el\/#\/schema\/logo\/image\/","url":"https:\/\/beonmove.gr\/wp-content\/uploads\/2020\/02\/Logo_200.png","contentUrl":"https:\/\/beonmove.gr\/wp-content\/uploads\/2020\/02\/Logo_200.png","width":200,"height":173,"caption":"BeOnMove"},"image":{"@id":"https:\/\/beonmove.gr\/el\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beonmove\/","https:\/\/www.instagram.com\/be_on_move\/","https:\/\/www.youtube.com\/channel\/UC5WA7H8ownrvq7OaoVBDmSQ"]}]}},"_links":{"self":[{"href":"https:\/\/beonmove.gr\/el\/wp-json\/wp\/v2\/product_cat\/462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beonmove.gr\/el\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/beonmove.gr\/el\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/beonmove.gr\/el\/wp-json\/wp\/v2\/product_cat\/460"}],"wp:post_type":[{"href":"https:\/\/beonmove.gr\/el\/wp-json\/wp\/v2\/product?product_cat=462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}